{"id":5123,"date":"2025-06-01T17:54:40","date_gmt":"2025-06-01T09:54:40","guid":{"rendered":"https:\/\/selectpacktech.com\/?post_type=product&#038;p=5123"},"modified":"2025-06-01T19:26:58","modified_gmt":"2025-06-01T11:26:58","slug":"mobile-pallet-wrapper-gecko-s2","status":"publish","type":"product","link":"https:\/\/selectpacktech.com\/de\/product\/mobile-pallet-wrapper-gecko-s2\/","title":{"rendered":"Mobile Palettenwickler Gecko S2"},"content":{"rendered":"<h2 class=\"wp-block-heading\" style=\"font-size:23px\">Mechanischer Parameter<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th class=\"has-text-align-left\" data-align=\"left\">Modell<\/th><th class=\"has-text-align-left\" data-align=\"left\">SelectAuto\/Gecko<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-left\" data-align=\"left\">Batterie<\/td><td class=\"has-text-align-left\" data-align=\"left\">2 x 12V100Ah<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Reisegeschwindigkeit<\/td><td class=\"has-text-align-left\" data-align=\"left\">35 \u2013 75 m\/min<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Liftgeschwindigkeit<\/td><td class=\"has-text-align-left\" data-align=\"left\">2 \u2013 5,5 m\/min<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Umh\u00fcllungsh\u00f6he<\/td><td class=\"has-text-align-left\" data-align=\"left\">Standard: 2000 mm<br>Optional: 2400 \/ 2600 \/ 2800 \/ 3000 mm<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Filmwagentyp<\/td><td class=\"has-text-align-left\" data-align=\"left\">Vorgedehnter offener T\u00fcrwagen<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Vordehnungsverh\u00e4ltnis<\/td><td class=\"has-text-align-left\" data-align=\"left\">2.5<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Eingangsspannung<\/td><td class=\"has-text-align-left\" data-align=\"left\">220 V, 1 pH<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Frequenz<\/td><td class=\"has-text-align-left\" data-align=\"left\">50\/60 Hz<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Installierte Leistung<\/td><td class=\"has-text-align-left\" data-align=\"left\">1<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Anzahl der Wicklungen pro Geb\u00fchr<\/td><td class=\"has-text-align-left\" data-align=\"left\">150 \u2013 250 Paletten pro Ladung<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Maximale Filmrollengr\u00f6\u00dfe<\/td><td class=\"has-text-align-left\" data-align=\"left\">500 \u00d7 250 mm (Kern-\u00d8 76 mm)<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Gewicht der Filmrolle<\/td><td class=\"has-text-align-left\" data-align=\"left\">15 kg<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Filmdicke<\/td><td class=\"has-text-align-left\" data-align=\"left\">15 \u2013 25 \u03bcm<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Gabelzugriff<\/td><td class=\"has-text-align-left\" data-align=\"left\">Zugang \u00fcber die linke und rechte Gabel<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:23px\">Elektrische Konfiguration<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th class=\"has-text-align-left\" data-align=\"left\">Artikel<\/th><th class=\"has-text-align-left\" data-align=\"left\">Marke<\/th><th class=\"has-text-align-left\" data-align=\"left\">Herkunft<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-left\" data-align=\"left\">HMI-Touchpanel<\/td><td class=\"has-text-align-left\" data-align=\"left\">S1-S3000-T<\/td><td class=\"has-text-align-left\" data-align=\"left\">China<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Frequenzumrichter<\/td><td class=\"has-text-align-left\" data-align=\"left\">S1-D3000<\/td><td class=\"has-text-align-left\" data-align=\"left\">China<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Startknopf (gr\u00fcn)<\/td><td class=\"has-text-align-left\" data-align=\"left\">Gangbo<\/td><td class=\"has-text-align-left\" data-align=\"left\">China<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Stoppknopf (rot)&nbsp;<\/td><td class=\"has-text-align-left\" data-align=\"left\">Gangbo<\/td><td class=\"has-text-align-left\" data-align=\"left\">China<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Not aus<\/td><td class=\"has-text-align-left\" data-align=\"left\">Gangbo<\/td><td class=\"has-text-align-left\" data-align=\"left\">China<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Endschalter<\/td><td class=\"has-text-align-left\" data-align=\"left\">Delixi<\/td><td class=\"has-text-align-left\" data-align=\"left\">China<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Fotoelektrischer Schalter<\/td><td class=\"has-text-align-left\" data-align=\"left\">OMRON<br>GK3-DR250J<\/td><td class=\"has-text-align-left\" data-align=\"left\">China<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Spannungssensor<\/td><td class=\"has-text-align-left\" data-align=\"left\">S1-QWAA-BM4-5kg<\/td><td class=\"has-text-align-left\" data-align=\"left\">China<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Gleichstrom-Traktionsmotor<\/td><td class=\"has-text-align-left\" data-align=\"left\">Zibo Gleichstrommotor<\/td><td class=\"has-text-align-left\" data-align=\"left\">China<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Hubgetriebe<\/td><td class=\"has-text-align-left\" data-align=\"left\">MYCRO<\/td><td class=\"has-text-align-left\" data-align=\"left\">China<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">Filmwagenmotor<\/td><td class=\"has-text-align-left\" data-align=\"left\">Zibo Gleichstrommotor<\/td><td class=\"has-text-align-left\" data-align=\"left\">China<\/td><\/tr><\/tbody><\/table><\/figure>","protected":false},"excerpt":{"rendered":"<p>Die mobile Palettenwickelmaschine SelectAuto\/Gecko bietet flexibles und bedienersicheres Stretchwickeln f\u00fcr Paletten aller Gr\u00f6\u00dfen \u2013 ganz ohne Drehteller. Dank leistungsstarkem Akku, integriertem Touchscreen und optionalem automatischem Folienabschneider ist sie die ideale L\u00f6sung f\u00fcr Lager mit begrenztem Platzangebot oder hohem Durchsatz.<\/p>","protected":false},"featured_media":5126,"template":"","meta":[],"product_brand":[],"product_cat":[65,85],"product_tag":[156],"class_list":["post-5123","product","type-product","status-publish","has-post-thumbnail","product_cat-automation","product_cat-machine","product_tag-gecko","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/selectpacktech.com\/de\/wp-json\/wp\/v2\/product\/5123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selectpacktech.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/selectpacktech.com\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/selectpacktech.com\/de\/wp-json\/wp\/v2\/product\/5123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/selectpacktech.com\/de\/wp-json\/wp\/v2\/media\/5126"}],"wp:attachment":[{"href":"https:\/\/selectpacktech.com\/de\/wp-json\/wp\/v2\/media?parent=5123"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/selectpacktech.com\/de\/wp-json\/wp\/v2\/product_brand?post=5123"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/selectpacktech.com\/de\/wp-json\/wp\/v2\/product_cat?post=5123"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/selectpacktech.com\/de\/wp-json\/wp\/v2\/product_tag?post=5123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}